{"id":15873,"date":"2023-03-07T11:35:25","date_gmt":"2023-03-07T10:35:25","guid":{"rendered":"https:\/\/www.consultingcheck.com\/\/topics\/modelos-de-teoria-de-juegos\/15873\/"},"modified":"2023-03-07T11:35:25","modified_gmt":"2023-03-07T10:35:25","slug":"modelos-de-teoria-de-juegos","status":"publish","type":"jask_topic","link":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/","title":{"rendered":"Modelos de teor\u00eda de juegos"},"content":{"rendered":"<p>Los sistemas se explican a trav\u00e9s de las interacciones entre sus elementos. Esto es exactamente lo que ocurre en los sistemas sociales, incluidas las empresas. <\/p><p>La teor\u00eda de los juegos se ocupa de la explicaci\u00f3n de las interacciones, en particular de la cuesti\u00f3n de c\u00f3mo se toman las decisiones en la interdependencia y qu\u00e9 efectos consiguen. Proporciona modelos para juegos \u00fanicos y repetidos, para informaci\u00f3n asim\u00e9trica, para juegos de se\u00f1alizaci\u00f3n y para juegos evolutivos, que son adecuados para reconocer patrones b\u00e1sicos en las interacciones y para evaluar sistem\u00e1ticamente las opciones de acci\u00f3n. Por lo tanto, la teor\u00eda de los juegos se ofrece como una disciplina \u00fatil tanto para explicar los sistemas como para una gesti\u00f3n con sentido sist\u00e9mico.<\/p><p>Son interesantes las situaciones de toma de decisiones cuyos resultados se derivan de las interacciones con otros decisores, es decir, situaciones en las que la decisi\u00f3n de terceros influye en el resultado de la propia decisi\u00f3n. Los resultados de estas situaciones de toma de decisiones en las interdependencias suelen ser sorprendentes porque el proceso de toma de decisiones es inestable. Una comprensi\u00f3n insuficiente de las interrelaciones, el af\u00e1n oportunista de los participantes por obtener ventajas individuales o la desconfianza conducen repetidamente a situaciones en la vida cotidiana de las empresas en las que no se alcanza un nivel \u00f3ptimo en la cooperaci\u00f3n, aunque sea posible.<\/p><p>Los instrumentos de la teor\u00eda de juegos pueden ser un apoyo importante tanto para la comprensi\u00f3n como para el dise\u00f1o de interacciones cuyos resultados surgen en dependencia mutua. Especialmente en el dise\u00f1o de estructuras de acci\u00f3n sist\u00e9micas en las organizaciones, resulta \u00fatil utilizar los enfoques de la teor\u00eda de los juegos para visualizar las posibilidades de acci\u00f3n y sus efectos con el trasfondo de la \u00abgran imagen\u00bb en el c\u00edrculo de todos los implicados. As\u00ed, madura la sensibilidad para tomar decisiones que aporten el mejor resultado para todos los participantes.<\/p><p>Lea c\u00f3mo <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/uso-de-la-teoria-de-los-juegos-en-la-toma-de-decisiones\/15874\/\" title=\"Nutzen der Spieltheorie bei Entscheidungen\">la teor\u00eda de los juegos puede ayudar<\/a> a mejorar los resultados para todas las partes interesadas. Enriqu\u00e9zcase tambi\u00e9n con conocimientos \u00fatiles sobre <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/equilibrio-de-nash\/15875\/\" title=\"Das Nash-Gleichgewicht f\u00fcr kalkulierbare Ergebnisse\">el equilibrio de Nash<\/a> y <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/equilibrio-optimo-de-pareto\/15876\/\" title=\"Das pareto-optimale Gleichgewicht\">el equilibrio pareto-\u00f3ptimo<\/a>. Aprenda tambi\u00e9n cu\u00e1ndo se recomienda una <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/estrategia-de-dominio\/15877\/\" title=\"Die dominierende Strategie\">estrategia dominante<\/a> y cu\u00e1ndo una <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/estrategia-mixta\/15878\/\" title=\"Die gemischte Strategie\">estrategia mixta<\/a>. <\/p><p>Aproveche tambi\u00e9n para conocer los principios esenciales de la toma de decisiones. Lea sobre el <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/el-principio-maximin-segun-john-von-neumann\/15880\/\" title=\"Das Maximin-Prinzip nach John von Neumann\">principio minimax<\/a>, <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/principio-de-laplace\/15882\/\" title=\"Das Laplace-Prinzip\">el principio de Laplace<\/a>, el <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/principio-de-arrepentimiento-regret-prinzip\/15883\/\" title=\"Das Regret-Prinzip\">principio de arrepentimiento<\/a>, el <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/principio-de-utilidad-subjetiva-esperada-seu\/15884\/\" title=\"Das Subjective-Expected-Utility-Prinzip (SEU)\">principio de utilidad subjetiva esperada<\/a> y el <a class=\"topic-link\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/principio-de-utilidad-subjetiva-esperada-seu\/15884\/\" title=\"Das Subjective-Expected-Utility-Prinzip (SEU)\">principio de auto-vinculaci\u00f3n de Thomas C. Schelling<\/a>.<\/p>","protected":false},"featured_media":0,"parent":15865,"menu_order":21600,"template":"","meta":{"_links_to":"","_links_to_target":""},"jask_topic_categories":[1436],"class_list":["post-15873","jask_topic","type-jask_topic","status-publish","hentry","jask_topic_categories-spieltheoretische-modelle-entscheidungen-ausenfuhrung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelos de teor\u00eda de juegos - consultingcheck<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelos de teor\u00eda de juegos - consultingcheck\" \/>\n<meta property=\"og:description\" content=\"Los sistemas se explican a trav\u00e9s de las interacciones entre sus elementos. Esto es exactamente lo que ocurre en los sistemas sociales, incluidas las empresas. La teor\u00eda de los juegos se ocupa de la explicaci\u00f3n de las interacciones, en particular de la cuesti\u00f3n de c\u00f3mo se toman las decisiones en la interdependencia y qu\u00e9 efectos ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/\" \/>\n<meta property=\"og:site_name\" content=\"consultingcheck\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630-1024x538.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630-1024x538.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topics\\\/modelos-de-teoria-de-juegos\\\/15873\\\/\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topics\\\/modelos-de-teoria-de-juegos\\\/15873\\\/\",\"name\":\"Modelos de teor\u00eda de juegos - consultingcheck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/#website\"},\"datePublished\":\"2023-03-07T10:35:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topics\\\/modelos-de-teoria-de-juegos\\\/15873\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topics\\\/modelos-de-teoria-de-juegos\\\/15873\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topics\\\/modelos-de-teoria-de-juegos\\\/15873\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/topic\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelos de teor\u00eda de juegos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/\",\"name\":\"consultingcheck\",\"description\":\"Vernetzt gedacht. Entzaubert. Hands-on.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consultingcheck.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelos de teor\u00eda de juegos - consultingcheck","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/","og_locale":"es_ES","og_type":"article","og_title":"Modelos de teor\u00eda de juegos - consultingcheck","og_description":"Los sistemas se explican a trav\u00e9s de las interacciones entre sus elementos. Esto es exactamente lo que ocurre en los sistemas sociales, incluidas las empresas. La teor\u00eda de los juegos se ocupa de la explicaci\u00f3n de las interacciones, en particular de la cuesti\u00f3n de c\u00f3mo se toman las decisiones en la interdependencia y qu\u00e9 efectos ...","og_url":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/","og_site_name":"consultingcheck","og_image":[{"url":"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630-1024x538.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630-1024x538.jpg","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/","url":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/","name":"Modelos de teor\u00eda de juegos - consultingcheck","isPartOf":{"@id":"https:\/\/www.consultingcheck.com\/es\/#website"},"datePublished":"2023-03-07T10:35:25+00:00","breadcrumb":{"@id":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consultingcheck.com\/es\/topics\/modelos-de-teoria-de-juegos\/15873\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.consultingcheck.com\/es\/"},{"@type":"ListItem","position":2,"name":"Themen","item":"https:\/\/www.consultingcheck.com\/es\/topic\/"},{"@type":"ListItem","position":3,"name":"Modelos de teor\u00eda de juegos"}]},{"@type":"WebSite","@id":"https:\/\/www.consultingcheck.com\/es\/#website","url":"https:\/\/www.consultingcheck.com\/es\/","name":"consultingcheck","description":"Vernetzt gedacht. Entzaubert. Hands-on.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consultingcheck.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/jask_topic\/15873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/jask_topic"}],"about":[{"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/types\/jask_topic"}],"version-history":[{"count":0,"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/jask_topic\/15873\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/jask_topic\/15865"}],"wp:attachment":[{"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/media?parent=15873"}],"wp:term":[{"taxonomy":"jask_topic_categories","embeddable":true,"href":"https:\/\/www.consultingcheck.com\/es\/wp-json\/wp\/v2\/jask_topic_categories?post=15873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}