{"id":1024,"count":2,"description":"","link":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/","name":"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung","slug":"insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en","taxonomy":"jask_topic_categories","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/\" \/>\n<meta property=\"og:site_name\" content=\"consultingcheck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/topic-cat\\\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\\\/\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/topic-cat\\\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\\\/\",\"name\":\"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/topic-cat\\\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/topic-cat\\\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/\",\"name\":\"consultingcheck\",\"description\":\"Vernetzt gedacht. Entzaubert. Hands-on.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consultingcheck.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck","og_url":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/","og_site_name":"consultingcheck","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/","url":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/","name":"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung Archive - consultingcheck","isPartOf":{"@id":"https:\/\/www.consultingcheck.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.consultingcheck.com\/en\/topic-cat\/insolvenzantragspflicht-und-geschaeftsfuehrerhaftung-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.consultingcheck.com\/en\/"},{"@type":"ListItem","position":2,"name":"Insolvenzantragspflicht und Gesch\u00e4ftsf\u00fchrerhaftung"}]},{"@type":"WebSite","@id":"https:\/\/www.consultingcheck.com\/en\/#website","url":"https:\/\/www.consultingcheck.com\/en\/","name":"consultingcheck","description":"Vernetzt gedacht. Entzaubert. Hands-on.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consultingcheck.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.consultingcheck.com\/en\/wp-json\/wp\/v2\/jask_topic_categories\/1024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consultingcheck.com\/en\/wp-json\/wp\/v2\/jask_topic_categories"}],"about":[{"href":"https:\/\/www.consultingcheck.com\/en\/wp-json\/wp\/v2\/taxonomies\/jask_topic_categories"}],"wp:post_type":[{"href":"https:\/\/www.consultingcheck.com\/en\/wp-json\/wp\/v2\/jask_topic?jask_topic_categories=1024"},{"href":"https:\/\/www.consultingcheck.com\/en\/wp-json\/wp\/v2\/product?jask_topic_categories=1024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}