{"id":214,"date":"2021-11-05T06:13:40","date_gmt":"2021-11-05T05:13:40","guid":{"rendered":"https:\/\/www.consultingcheck.com\/topics\/brainstorming-214"},"modified":"2022-05-12T15:46:20","modified_gmt":"2022-05-12T13:46:20","slug":"brainstorming-als-kreativitaetstechnik","status":"publish","type":"jask_topic","link":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/","title":{"rendered":"Brainstorming als Kreativit\u00e4tstechnik"},"content":{"rendered":"\n<p>Die wohl bekannteste intuitive Methode ist das Brainstorming, eine bereits 1939 von Alex F. Osborn entwickelte Methode, die anregt, ganz frei und unvoreingenommen an eine Problemstellung heranzugehen, sich in einer m\u00f6glichst heterogen zusammengesetzten Gruppe voneinander inspirieren zu lassen und kreative Ideen k\u00fchn miteinander zu kombinieren. Brainstorming hilft, bekannte Denkpfade und -strukturen zu verlassen und von au\u00dfen auf die Problemstellung zu blicken. Das ist wichtig, weil mit unver\u00e4ndertem Denken kaum wirklich neue L\u00f6sungswege gefunden werden k\u00f6nnen. <\/p>\n","protected":false},"featured_media":0,"parent":213,"menu_order":10800,"template":"","meta":{"_links_to":"","_links_to_target":""},"jask_topic_categories":[184],"class_list":["post-214","jask_topic","type-jask_topic","status-publish","hentry","jask_topic_categories-brainstorming"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brainstorming als Kreativit\u00e4tstechnik - consultingcheck<\/title>\n<meta name=\"description\" content=\"Die wohl bekannteste intuitive Kreativit\u00e4tstechnik: Brainstorming hilft bei der freien Probleml\u00f6sung. Erfahren Sie jetzt mehr dar\u00fcber.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brainstorming als Kreativit\u00e4tstechnik\" \/>\n<meta property=\"og:description\" content=\"F\u00fcr eine freie Probleml\u00f6sung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/\" \/>\n<meta property=\"og:site_name\" content=\"consultingcheck\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-12T13:46:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Brainstorming als Kreativit\u00e4tstechnik\" \/>\n<meta name=\"twitter:description\" content=\"F\u00fcr eine freie Probleml\u00f6sung\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topics\\\/brainstorming-als-kreativitaetstechnik\\\/214\\\/\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topics\\\/brainstorming-als-kreativitaetstechnik\\\/214\\\/\",\"name\":\"Brainstorming als Kreativit\u00e4tstechnik - consultingcheck\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/#website\"},\"datePublished\":\"2021-11-05T05:13:40+00:00\",\"dateModified\":\"2022-05-12T13:46:20+00:00\",\"description\":\"Die wohl bekannteste intuitive Kreativit\u00e4tstechnik: Brainstorming hilft bei der freien Probleml\u00f6sung. Erfahren Sie jetzt mehr dar\u00fcber.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topics\\\/brainstorming-als-kreativitaetstechnik\\\/214\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topics\\\/brainstorming-als-kreativitaetstechnik\\\/214\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topics\\\/brainstorming-als-kreativitaetstechnik\\\/214\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Themen\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stabilisierung: Sichern Sie die Existenz Ihres Unternehmens\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Innovation: Ist Ihr Unternehmen innovativ?\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/innovation-ist-ihr-unternehmen-innovativ\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Innovationsprozesse gezielt umsetzen\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/innovation-ist-ihr-unternehmen-innovativ\\\/innovationsprozesse-gezielt-umsetzen\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Kreativit\u00e4t f\u00fcr Innovationen entwickeln\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/innovation-ist-ihr-unternehmen-innovativ\\\/innovationsprozesse-gezielt-umsetzen\\\/kreativitaet-fuer-innovationen-entwickeln\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"Kreativit\u00e4tstechniken zielgerichtet einsetzen\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/innovation-ist-ihr-unternehmen-innovativ\\\/innovationsprozesse-gezielt-umsetzen\\\/kreativitaet-fuer-innovationen-entwickeln\\\/kreativitaetstechniken-zielgerichtet-einsetzen\\\/\"},{\"@type\":\"ListItem\",\"position\":8,\"name\":\"Intuitive Methoden f\u00fcr mehr Kreativit\u00e4t\",\"item\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/topic\\\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\\\/innovation-ist-ihr-unternehmen-innovativ\\\/innovationsprozesse-gezielt-umsetzen\\\/kreativitaet-fuer-innovationen-entwickeln\\\/kreativitaetstechniken-zielgerichtet-einsetzen\\\/intuitive-methoden-fuer-mehr-kreativitaet\\\/\"},{\"@type\":\"ListItem\",\"position\":9,\"name\":\"Brainstorming als Kreativit\u00e4tstechnik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/\",\"name\":\"consultingcheck\",\"description\":\"Vernetzt gedacht. Entzaubert. Hands-on.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.consultingcheck.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brainstorming als Kreativit\u00e4tstechnik - consultingcheck","description":"Die wohl bekannteste intuitive Kreativit\u00e4tstechnik: Brainstorming hilft bei der freien Probleml\u00f6sung. Erfahren Sie jetzt mehr dar\u00fcber.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/","og_locale":"de_DE","og_type":"article","og_title":"Brainstorming als Kreativit\u00e4tstechnik","og_description":"F\u00fcr eine freie Probleml\u00f6sung","og_url":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/","og_site_name":"consultingcheck","article_modified_time":"2022-05-12T13:46:20+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Brainstorming als Kreativit\u00e4tstechnik","twitter_description":"F\u00fcr eine freie Probleml\u00f6sung","twitter_image":"https:\/\/www.consultingcheck.com\/wp-content\/uploads\/2022\/04\/og-bild_1200x630.jpg","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/","url":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/","name":"Brainstorming als Kreativit\u00e4tstechnik - consultingcheck","isPartOf":{"@id":"https:\/\/www.consultingcheck.com\/de\/#website"},"datePublished":"2021-11-05T05:13:40+00:00","dateModified":"2022-05-12T13:46:20+00:00","description":"Die wohl bekannteste intuitive Kreativit\u00e4tstechnik: Brainstorming hilft bei der freien Probleml\u00f6sung. Erfahren Sie jetzt mehr dar\u00fcber.","breadcrumb":{"@id":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.consultingcheck.com\/de\/topics\/brainstorming-als-kreativitaetstechnik\/214\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.consultingcheck.com\/de\/"},{"@type":"ListItem","position":2,"name":"Themen","item":"https:\/\/www.consultingcheck.com\/de\/topic\/"},{"@type":"ListItem","position":3,"name":"Stabilisierung: Sichern Sie die Existenz Ihres Unternehmens","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/"},{"@type":"ListItem","position":4,"name":"Innovation: Ist Ihr Unternehmen innovativ?","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/innovation-ist-ihr-unternehmen-innovativ\/"},{"@type":"ListItem","position":5,"name":"Innovationsprozesse gezielt umsetzen","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/innovation-ist-ihr-unternehmen-innovativ\/innovationsprozesse-gezielt-umsetzen\/"},{"@type":"ListItem","position":6,"name":"Kreativit\u00e4t f\u00fcr Innovationen entwickeln","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/innovation-ist-ihr-unternehmen-innovativ\/innovationsprozesse-gezielt-umsetzen\/kreativitaet-fuer-innovationen-entwickeln\/"},{"@type":"ListItem","position":7,"name":"Kreativit\u00e4tstechniken zielgerichtet einsetzen","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/innovation-ist-ihr-unternehmen-innovativ\/innovationsprozesse-gezielt-umsetzen\/kreativitaet-fuer-innovationen-entwickeln\/kreativitaetstechniken-zielgerichtet-einsetzen\/"},{"@type":"ListItem","position":8,"name":"Intuitive Methoden f\u00fcr mehr Kreativit\u00e4t","item":"https:\/\/www.consultingcheck.com\/de\/topic\/stabilisierung-sichern-sie-die-existenz-ihres-unternehmens\/innovation-ist-ihr-unternehmen-innovativ\/innovationsprozesse-gezielt-umsetzen\/kreativitaet-fuer-innovationen-entwickeln\/kreativitaetstechniken-zielgerichtet-einsetzen\/intuitive-methoden-fuer-mehr-kreativitaet\/"},{"@type":"ListItem","position":9,"name":"Brainstorming als Kreativit\u00e4tstechnik"}]},{"@type":"WebSite","@id":"https:\/\/www.consultingcheck.com\/de\/#website","url":"https:\/\/www.consultingcheck.com\/de\/","name":"consultingcheck","description":"Vernetzt gedacht. Entzaubert. Hands-on.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consultingcheck.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic"}],"about":[{"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/types\/jask_topic"}],"version-history":[{"count":3,"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic\/214\/revisions"}],"predecessor-version":[{"id":4851,"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic\/214\/revisions\/4851"}],"up":[{"embeddable":true,"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic\/213"}],"wp:attachment":[{"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"jask_topic_categories","embeddable":true,"href":"https:\/\/www.consultingcheck.com\/de\/wp-json\/wp\/v2\/jask_topic_categories?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}